{"id":20,"count":1,"description":"","link":"https:\/\/flamingolilled.ee\/en\/product-category\/loikelilled\/","name":"Flowers","slug":"loikelilled","taxonomy":"product_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u00f5ikelilled - Flamingo Lillepood<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flamingolilled.ee\/en\/product-category\/loikelilled\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00f5ikelilled - Flamingo Lillepood\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flamingolilled.ee\/en\/product-category\/loikelilled\/\" \/>\n<meta property=\"og:site_name\" content=\"Flamingo Lillepood\" \/>\n<meta property=\"og:image\" content=\"https:\/\/flamingolilled.ee\/wp-content\/uploads\/2024\/01\/logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"542\" \/>\n\t<meta property=\"og:image:height\" content=\"257\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/flamingolilled.ee\/tootekategooria\/loikelilled\/\",\"url\":\"https:\/\/flamingolilled.ee\/tootekategooria\/loikelilled\/\",\"name\":\"L\u00f5ikelilled - Flamingo Lillepood\",\"isPartOf\":{\"@id\":\"https:\/\/flamingolilled.ee\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/flamingolilled.ee\/tootekategooria\/loikelilled\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/flamingolilled.ee\/tootekategooria\/loikelilled\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/flamingolilled.ee\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u00f5ikelilled\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/flamingolilled.ee\/#website\",\"url\":\"https:\/\/flamingolilled.ee\/\",\"name\":\"Flamingo Lillepood\",\"description\":\"P\u00f5lva ilusamad lilled\",\"publisher\":{\"@id\":\"https:\/\/flamingolilled.ee\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/flamingolilled.ee\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/flamingolilled.ee\/#organization\",\"name\":\"Maidro O\u00dc\",\"alternateName\":\"Flamingi Lillepood\",\"url\":\"https:\/\/flamingolilled.ee\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/flamingolilled.ee\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/flamingolilled.ee\/wp-content\/uploads\/2024\/01\/logo.png\",\"contentUrl\":\"https:\/\/flamingolilled.ee\/wp-content\/uploads\/2024\/01\/logo.png\",\"width\":542,\"height\":257,\"caption\":\"Maidro O\u00dc\"},\"image\":{\"@id\":\"https:\/\/flamingolilled.ee\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/flamingolilled\",\"https:\/\/www.instagram.com\/flamingolilled\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u00f5ikelilled - Flamingo Lillepood","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flamingolilled.ee\/en\/product-category\/loikelilled\/","og_locale":"en_GB","og_type":"article","og_title":"L\u00f5ikelilled - Flamingo Lillepood","og_url":"https:\/\/flamingolilled.ee\/en\/product-category\/loikelilled\/","og_site_name":"Flamingo Lillepood","og_image":[{"width":542,"height":257,"url":"https:\/\/flamingolilled.ee\/wp-content\/uploads\/2024\/01\/logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/flamingolilled.ee\/tootekategooria\/loikelilled\/","url":"https:\/\/flamingolilled.ee\/tootekategooria\/loikelilled\/","name":"L\u00f5ikelilled - Flamingo Lillepood","isPartOf":{"@id":"https:\/\/flamingolilled.ee\/#website"},"breadcrumb":{"@id":"https:\/\/flamingolilled.ee\/tootekategooria\/loikelilled\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/flamingolilled.ee\/tootekategooria\/loikelilled\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/flamingolilled.ee\/"},{"@type":"ListItem","position":2,"name":"L\u00f5ikelilled"}]},{"@type":"WebSite","@id":"https:\/\/flamingolilled.ee\/#website","url":"https:\/\/flamingolilled.ee\/","name":"Flamingo Lillepood","description":"P\u00f5lva ilusamad lilled","publisher":{"@id":"https:\/\/flamingolilled.ee\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flamingolilled.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/flamingolilled.ee\/#organization","name":"Maidro O\u00dc","alternateName":"Flamingi Lillepood","url":"https:\/\/flamingolilled.ee\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/flamingolilled.ee\/#\/schema\/logo\/image\/","url":"https:\/\/flamingolilled.ee\/wp-content\/uploads\/2024\/01\/logo.png","contentUrl":"https:\/\/flamingolilled.ee\/wp-content\/uploads\/2024\/01\/logo.png","width":542,"height":257,"caption":"Maidro O\u00dc"},"image":{"@id":"https:\/\/flamingolilled.ee\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/flamingolilled","https:\/\/www.instagram.com\/flamingolilled\/"]}]}},"_links":{"self":[{"href":"https:\/\/flamingolilled.ee\/en\/wp-json\/wp\/v2\/product_cat\/20","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flamingolilled.ee\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/flamingolilled.ee\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/flamingolilled.ee\/en\/wp-json\/wp\/v2\/product?product_cat=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}